{"id":26162,"date":"2021-07-07T11:45:00","date_gmt":"2021-07-07T14:45:00","guid":{"rendered":"https:\/\/www.infobioquimica.com\/new\/?p=26162"},"modified":"2021-07-07T11:06:20","modified_gmt":"2021-07-07T14:06:20","slug":"reporte-epidemiologico-464","status":"publish","type":"post","link":"https:\/\/www.infobioquimica.com\/new\/2021\/07\/07\/reporte-epidemiologico-464\/","title":{"rendered":"Reporte Epidemiol\u00f3gico 464"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Reporte epidemiol\u00f3gico semanal<\/h2><h3 class=\"wp-block-heading\">Mi\u00e9rcoles 7 de julio de 2021<\/h3><ul class=\"wp-block-list\"><li><strong>SARS-CoV-2.<\/strong> El Proyecto Argentino Interinstitucional de gen\u00f3mica de SARS-CoV-2 (PAIS) considera que el linaje C.37 (variante andina) deber\u00eda ser considerada al menos, \u201cvariante de inter\u00e9s regional\u201d, dado el incremento sostenido de su frecuencia de detecci\u00f3n en la regi\u00f3n del \u00c1rea Metropolitana de Buenos Aires.<\/li><li><strong>COVID-19.<\/strong> El tratamiento con esteroides es clave para salvar a pacientes con COVID-19 en estado grave, pero, seg\u00fan los expertos, estos f\u00e1rmacos reducen tambi\u00e9n la inmunidad de los pacientes y aumentan sus niveles de az\u00facar en sangre, y se asocian a infecciones f\u00fangicas.<\/li><li><strong>Barbijos. <\/strong>Un nuevo lote de datos de un gran estudio de trabajadores de la salud en todo Estados Unidos ayud\u00f3 a impulsar a los Centros para el Control y la Prevenci\u00f3n de Enfermedades a decir que las personas completamente vacunadas pueden no usar barbijo en la mayor\u00eda de las circunstancias.<\/li><\/ul><div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/infobioquimica.com\/abc\/El Microscopio 464 - Reporte epidemiologico.mp3\"><\/audio><\/figure>","protected":false},"excerpt":{"rendered":"<p>Reporte epidemiol\u00f3gico semanal Mi\u00e9rcoles 7 de julio de 2021 SARS-CoV-2. El Proyecto Argentino Interinstitucional de gen\u00f3mica de SARS-CoV-2 (PAIS) considera que el linaje C.37 (variante andina) deber\u00eda ser considerada al menos, \u201cvariante de inter\u00e9s regional\u201d, dado el incremento sostenido de su frecuencia de detecci\u00f3n en la regi\u00f3n del \u00c1rea Metropolitana de Buenos Aires. COVID-19. El [&hellip;]<\/p>\n","protected":false},"author":2620,"featured_media":25479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[2,705,12],"tags":[],"class_list":["post-26162","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-radio","category-reporte-epidemiologico"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/26162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/users\/2620"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/comments?post=26162"}],"version-history":[{"count":4,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/26162\/revisions"}],"predecessor-version":[{"id":26207,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/26162\/revisions\/26207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/media\/25479"}],"wp:attachment":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/media?parent=26162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/categories?post=26162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/tags?post=26162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}