{"id":31041,"date":"2024-09-18T09:04:11","date_gmt":"2024-09-18T12:04:11","guid":{"rendered":"https:\/\/www.infobioquimica.com\/new\/?p=31041"},"modified":"2024-09-18T09:50:27","modified_gmt":"2024-09-18T12:50:27","slug":"radio-el-microscopio-segunda-decada-emision-625","status":"publish","type":"post","link":"https:\/\/www.infobioquimica.com\/new\/2024\/09\/18\/radio-el-microscopio-segunda-decada-emision-625\/","title":{"rendered":"Radio el Microscopio Segunda D\u00e9cada          Emisi\u00f3n 625"},"content":{"rendered":"<h3 class=\"wp-block-heading has-text-align-center\">Decisiones Inteligentes desde el Laboratorio: de Elegir Sabiamente a No Hacer. PEAD-ML de la AEBM-ML.<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"812\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-812x1024.jpg\" alt=\"\" class=\"wp-image-31033\" style=\"width:285px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-812x1024.jpg 812w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-238x300.jpg 238w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-768x969.jpg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-1218x1536.jpg 1218w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-696x878.jpg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-1068x1347.jpg 1068w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-333x420.jpg 333w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA-600x757.jpg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/FOTO-VERONICA.jpg 1459w\" sizes=\"auto, (max-width: 812px) 100vw, 812px\" \/><\/a><\/figure><\/div>\n\n<\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Ver\u00f3nica C\u00e1mara Hern\u00e1ndez es Licenciada y Doctora en Qu\u00edmica por la Universidad de Murcia. Especialista en Bioqu\u00edmica Cl\u00ednica en el Hospital Universitario de Getafe donde actualmente desempe\u00f1a su labor como Facultativo Especialista responsable del Laboratorio de Urgencias. Es Secretaria de la Asociaci\u00f3n Espa\u00f1ola de Biopatolog\u00eda M\u00e9dica-M\u00e9dica de Laboratorio (AEBM-ML) y a la vez Secretaria del Comit\u00e9 de Adecuaci\u00f3n de la Demanda y Decisiones Inteligentes (CADDI) de la AEBM-ML. Coordina el Programa de Evaluaci\u00f3n de Adecuaci\u00f3n de la Demanda en Medicina de Laboratorio (PEAD-ML). Ha participado en diversas publicaciones en revistas de difusi\u00f3n nacional e internacional, libros, cap\u00edtulos de libros y comunicaciones a congresos.<\/p>\n<p><a href=\"mailto:adecuacion@aebm.org\">adecuacion@aebm.org<\/a>\u00a0 Inscripci\u00f3n al PEAD-ML<\/p>\n<p><a href=\"https:\/\/form.jotform.com\/242101576797967\">https:\/\/form.jotform.com\/242101576797967<\/a><\/p>\n<p>\u00abDecisiones Inteligentes desde el LAboratorio: de elegir sabiamente a no hacer\u00bb \u00a0<a href=\"http:\/\/www.aebm.org\/images\/activos\/publicaciones\/2021\/Decisiones-inteligentes-desde-el-laboratorio-2-ed-2021_compressed.pdf\">www.aebm.org\/images\/activos\/publicaciones\/2021\/Decisiones-inteligentes-desde-el-laboratorio-2-ed-2021_compressed.pdf<\/a><\/p>\n<p>\u00a0<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PILDORA-Veronica-Camara-Hernandez-2.00.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PODCAST-Veronica-Camara-Hernandez-20.46-.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Microbiota y diabetes<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Marta Olivares es licenciada en Ciencia y Tecnolog\u00eda de los alimentos y&nbsp;doctora por la Universidad Polit\u00e9cnica de Valencia. Su investigaci\u00f3n&nbsp;se ha centrado en el estudio del potencial del microbioma para modular&nbsp;la salud humana en el contexto de enfermedades autoinmunes y&nbsp;metab\u00f3licas, como la obesidad y la diabetes tipo 2. Ha realizado&nbsp;estancias internacionales en la Academia de las Ciencias de la&nbsp;Rep\u00fablica Checa, la Universidad de Michigan y la Universidad cat\u00f3lica&nbsp;de Lovaina. Actualmente es investigadora en el IATA-CSIC donde dirige&nbsp;su propia l\u00ednea de investigaci\u00f3n.<\/p>\n<p>Alfonso Ben\u00edtez P\u00e1ez es Biologo y Bioqu\u00edmico con t\u00edtulo de Doctorado en Biolog\u00eda Molecular. Durante su carrera cient\u00edfica se ha especializado en el estudio de la gen\u00f3mica bacteriana y en los estudios del microbioma oral e intestinal humano. Tiene en su haber m\u00e1s de 60 publicaciones revisadas por pares en revistas especializadas y reconocidas en el campo, act\u00faa como editor asociado y revisor en varias revistas del \u00e1rea de microbiolog\u00eda, gastroenterolog\u00eda y nutrici\u00f3n cl\u00ednica; es autor de tres patentes que describen soluciones terap\u00e9uticas basadas en la microbiota humana y lleva 5 a\u00f1os liderando la l\u00ednea de investigaci\u00f3n \u00abInteracciones Dieta-Microbio-Hospedador en Salud Metab\u00f3lica\u00bb cuya labor la desempe\u00f1a en el Instituto de Agroqu\u00edmica y Tecnolog\u00eda de Alimentos del CSIC en Valencia, Espa\u00f1a.<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Marta-y-Alfonso.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"624\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Marta-y-Alfonso.jpg\" alt=\"\" class=\"wp-image-31036\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Marta-y-Alfonso.jpg 262w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Marta-y-Alfonso-126x300.jpg 126w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Marta-y-Alfonso-176x420.jpg 176w\" sizes=\"auto, (max-width: 262px) 100vw, 262px\" \/><\/a><\/figure><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PILDORA-Alfonso-Benitez-Paez-Marta-Olivares-1.49.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PODCAST-Alfonso-Benitez-Paez-Marta-Olivares-12.36.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Podr\u00eda la depresi\u00f3n diagnosticarse a trav\u00e9s de la sangre?<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-751x1024.jpg\" alt=\"\" class=\"wp-image-31032\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-751x1024.jpg 751w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-220x300.jpg 220w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-768x1048.jpg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-696x949.jpg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-1068x1457.jpg 1068w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-308x420.jpg 308w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray-600x818.jpg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Federico-Daray.jpg 1074w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Federico Manuel Daray es m\u00e9dico psiquiatra. Trabaja como investigador independiente en el Consejo Nacional de Investigaciones Cient\u00edficas y T\u00e9cnicas y es profesor adjunto en la Facultad de Medicina de la Universidad de Buenos Aires, adonde hizo su doctorado en Farmacolog\u00eda, completando su residencia en Salud Mental en el Hospital Braulio A. Moyano. Ha realizado estancias postdoctorales en la Universidad de Columbia y otras instituciones de renombre. Su investigaci\u00f3n se centra en los trastornos afectivos, la farmacogen\u00e9tica y el suicidio, habiendo dirigido m\u00faltiples proyectos financiados por organismos nacionales e internacionales, como la American Foundation for Suicide Prevention (AFSP) y el Brain &amp; Behavior Research Foundation&nbsp;(BBRF).<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PILDORA-Federico-Daray-1.23.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/PODCAST-Federico-Daray-15.23-.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading alignwide has-text-align-center\">XXI Encuentro de la Sociedad Europea de Inmunodeficiencias.<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Jacinta Bustamante es profesora titular de Biolog\u00eda Celular en la Universidad Paris Cit\u00e9. Es experta en inmunolog\u00eda celular y molecular, as\u00ed como en gen\u00e9tica humana de enfermedades infecciosas. Ha realizado destacadas contribuciones al campo de las enfermedades bacterianas como la susceptibilidad mendeliana a la enfermedad micobacteriana o MSMD, la enfermedad granulomatosa cr\u00f3nica y la enfermedad de Whipple. Es responsable del diagn\u00f3stico de EIP en inmunidad innata en pacientes que asisten al Centro de Estudio de Inmunodeficiencias Primarias del Hospital Necker para Ni\u00f1os Enfermos y coordinadora de salud, medicina y ciencias de la vida en el programa ECOS-NORD. Ha publicado m\u00e1s de 250 art\u00edculos en revistas y libros cient\u00edficos revisados por pares.<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Jacinta.jfif_.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"183\" height=\"275\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Jacinta.jfif_.jpg\" alt=\"\" class=\"wp-image-31043\" style=\"width:262px;height:auto\"\/><\/a><\/figure><\/div><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Audio-de-WhatsApp-2024-09-16-a-las-18.26.27_072d3e10.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Historia de cient\u00edficos<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/gALENO.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"220\" height=\"291\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/gALENO.jpg\" alt=\"\" class=\"wp-image-31035\" style=\"width:273px;height:auto\"\/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Claudio Galeno Nicon de P\u00e9rgamo, m\u00e1s conocido como Galeno, fue un m\u00e9dico, cirujano y fil\u00f3sofo griego del Imperio romano.\u200b Considerado uno de los m\u00e1s completos investigadores m\u00e9dicos de la Edad Antigua, sus puntos de vista dominaron la medicina europea a lo largo de m\u00e1s de mil a\u00f1os en campos como la anatom\u00eda,\u200b la fisiolog\u00eda, la patolog\u00eda, la farmacolog\u00eda\u200b y la neurolog\u00eda, as\u00ed como la filosof\u00eda\u200b y la l\u00f3gica.<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2024\/09\/Galeno-4.42.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Decisiones Inteligentes desde el Laboratorio: de Elegir Sabiamente a No Hacer. PEAD-ML de la AEBM-ML. Ver\u00f3nica C\u00e1mara Hern\u00e1ndez es Licenciada y Doctora en Qu\u00edmica por la Universidad de Murcia. Especialista en Bioqu\u00edmica Cl\u00ednica en el Hospital Universitario de Getafe donde actualmente desempe\u00f1a su labor como Facultativo Especialista responsable del Laboratorio de Urgencias. Es Secretaria de [&hellip;]<\/p>\n","protected":false},"author":14117,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[1080,5,26,2],"tags":[476,440,442,773,438,426],"class_list":["post-31041","post","type-post","status-publish","format-standard","hentry","category-emisiones-es","category-emisiones","category-noticias-bioquimicas","category-radio","tag-bioquimica","tag-el-microscopio","tag-radio","tag-radio-de-los-bioquimicos","tag-radio-el-microscopio","tag-reporte"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/31041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/users\/14117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/comments?post=31041"}],"version-history":[{"count":5,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/31041\/revisions"}],"predecessor-version":[{"id":31050,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/31041\/revisions\/31050"}],"wp:attachment":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/media?parent=31041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/categories?post=31041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/tags?post=31041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}