{"id":32233,"date":"2026-05-15T08:58:25","date_gmt":"2026-05-15T11:58:25","guid":{"rendered":"https:\/\/www.infobioquimica.com\/new\/?p=32233"},"modified":"2026-05-15T14:43:52","modified_gmt":"2026-05-15T17:43:52","slug":"radio-el-microscopio-segunda-decada-programa-661","status":"publish","type":"post","link":"https:\/\/www.infobioquimica.com\/new\/2026\/05\/15\/radio-el-microscopio-segunda-decada-programa-661\/","title":{"rendered":"Radio el Microscopio Segunda D\u00e9cada Programa 661"},"content":{"rendered":"<h3 class=\"wp-block-heading has-text-align-center\">Microbiolog\u00eda cl\u00ednica: Incursionando en la epidemiolog\u00eda molecular bacteriana<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"623\" height=\"890\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez.jpeg\" alt=\"\" class=\"wp-image-32212\" style=\"aspect-ratio:0.7000244081034903;width:282px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez.jpeg 623w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez-210x300.jpeg 210w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez-294x420.jpeg 294w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Fatima-Rodriguez-600x857.jpeg 600w\" sizes=\"auto, (max-width: 623px) 100vw, 623px\" \/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>F\u00e1tima Rodr\u00edguez Acosta es Bioqu\u00edmica Cl\u00ednica con Especializaci\u00f3n en Metodolog\u00eda de la Investigaci\u00f3n por en Instituto de Investigaciones en Ciencias de la Salud, UNA, Paraguay. Es Magister en Ciencias Biom\u00e9dicas por el Instituto de Investigaciones en Ciencias de la Salud, Paraguay, y Diplomada en Interpretacion del Antibiograma por la Universidad del Pacifico Privada, Es Doctora en Ciencias Biol\u00f3gicas (UDELAR-PEDECIBA) Universidad de la Rep\u00fablica, Facultad de Ciencias, Uruguay. Tiene tambi\u00e9n una Especializaci\u00f3n en Did\u00e1ctica de la Educaci\u00f3n Superior, UNA. Es Docente Investigador y Miembro del Comit\u00e9 de Certificaci\u00f3n de Especialidades Bioqu\u00edmicas por la Universidad Nacional de Asunci\u00f3n. Es Jefa del Dpto. de Microbiolog\u00eda en el Instituto de Investigaciones en Ciencias de la Salud, UNA \u2013 IICS. \u00a0<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PILDORA-Fatima-Rodriguez-2.31.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Fatima-Rodriguez-24.33.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Resistencia antimicrobiana y diagn\u00f3stico microbiol\u00f3gico r\u00e1pido<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Germ\u00e1n Esparza es Microbi\u00f3logo Cl\u00ednico de la Pontificia Universidad Javeriana de Bogot\u00e1, Colombia, adonde es profesor de Antimicrobianos en los programas de pre-grado y post grado en Microbiolog\u00eda M\u00e9dica. Es adem\u00e1s, profesor de la Residencia en Enfermedades Infecciosas de la Universidad del Rosario. Es miembro del Panel de Expertos en Microbiolog\u00eda de la CLSI de Estados Unidos y coordina el Comit\u00e9 de Microbiolog\u00eda Cl\u00ednica de la Asociaci\u00f3n Panamericana de Infectolog\u00eda.<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"618\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor-618x1024.jpg\" alt=\"\" class=\"wp-image-32213\" style=\"aspect-ratio:0.6035353535353535;width:266px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor-618x1024.jpg 618w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor-181x300.jpg 181w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor-253x420.jpg 253w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor-600x995.jpg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/German-esparza-2026-mejor.jpg 623w\" sizes=\"auto, (max-width: 618px) 100vw, 618px\" \/><\/a><\/figure><\/div><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PILDORA-German-Esparza-1.59.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-german-Esparza-21.58.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Monitoreo de terapia anticoagulante.<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Brenda-Zuniga.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"489\" height=\"789\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Brenda-Zuniga.jpg\" alt=\"\" class=\"wp-image-32211\" style=\"aspect-ratio:0.6197730956239871;width:254px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Brenda-Zuniga.jpg 489w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Brenda-Zuniga-186x300.jpg 186w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Brenda-Zuniga-260x420.jpg 260w\" sizes=\"auto, (max-width: 489px) 100vw, 489px\" \/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Brenda Sarai Zu\u00f1iga Ascencio es Licenciada en Qu\u00edmica Cl\u00ednica en la facultad de bioan\u00e1lisis de la Universidad Veracruzana, Xalapa, Veracruz. Es titular del Laboratorio cl\u00ednico del Instituto Nacional de Enfermedades Respiratorias Ismael Cosio Villegas y encargada del \u00e1rea de Coagulaci\u00f3n. Posee Certificado acreditado en hemostasia y trombosis por el Consejo Europeo de Acreditaci\u00f3n de Educaci\u00f3n M\u00e9dica Continua y ha participado en acreditaci\u00f3n bajo el est\u00e1ndar 15189 para laboratorios cl\u00ednicos en el \u00e1rea de coagulaci\u00f3n, Entidad Mexicana de Acreditaci\u00f3n. Es miembro activo de sociedades en hemostasia y trombosis (ISTH, CLAHT, SOMETH, CTH, SETH) y creadora de contenido en hemostasia y coagulaci\u00f3n en redes sociales. Participa como ponente en eventos nacionales e internacionales.<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PILDORA-Brenda-Sarai-Zuniga-Ascencio-2.13.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Brenda-Sarai-Zuniga-Ascencio-18.02.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Biolog\u00eda molecular en par\u00e1sitos.<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>La Dra. Gloria Le\u00f3n Avila es Magister en Inmunolog\u00eda por la ENCB adonde es profesora titular \u201cC\u201d en el posgrado de Ciencias Quimicobiol\u00f3gicas. Es Doctora en Gen\u00e9tica y Biolog\u00eda Molecular en el CINVESTAV, IPN y Postdoc por la Royal Holloway University of London. Su grupo de investigaci\u00f3n se enfoca en el estudio de la expresi\u00f3n de genes, prote\u00ednas de citoesqueleto, la caracterizaci\u00f3n de la peptidil tRNA hidrolasa\u00a0 en par\u00e1sitos protozoarios y la b\u00fasqueda de par\u00e1sitos de inter\u00e9s zoonotico en animales silvestres. Colabora con grupos de investigaci\u00f3n del CINVESTAV y el Hospital Ju\u00e1rez. Es miembro de la Sociedad Mexicana de Parasitolog\u00eda y forma parte del Sistema Nacional de Investigadores con nivel II.<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"610\" height=\"894\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz.jpg\" alt=\"\" class=\"wp-image-32214\" style=\"aspect-ratio:0.6823494423791822;width:297px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz.jpg 610w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz-205x300.jpg 205w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz-287x420.jpg 287w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gloria-de-la-Luz-600x879.jpg 600w\" sizes=\"auto, (max-width: 610px) 100vw, 610px\" \/><\/a><\/figure><\/div><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PILDORA-Gloria-de-la-Luz-Leon-Avila-1.46.mp3\"><\/audio><figcaption class=\"wp-element-caption\">P\u00edldora<\/figcaption><\/figure><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Gloria-de-la-Luz-Leon-Avila-26.19.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">CONQUILAB 2026<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"809\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-809x1024.jpeg\" alt=\"\" class=\"wp-image-32217\" style=\"aspect-ratio:0.7900554388622981;width:286px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-809x1024.jpeg 809w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-237x300.jpeg 237w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-768x972.jpeg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-696x881.jpeg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-332x420.jpeg 332w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero-600x759.jpeg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/jesus-alba-romero.jpeg 971w\" sizes=\"auto, (max-width: 809px) 100vw, 809px\" \/><\/a><\/figure><\/div>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-768x1024.jpeg\" alt=\"\" class=\"wp-image-32216\" style=\"width:311px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-768x1024.jpeg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-225x300.jpeg 225w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-1152x1536.jpeg 1152w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-696x928.jpeg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-1068x1424.jpeg 1068w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-315x420.jpeg 315w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026-600x800.jpeg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Ixschel-2026.jpeg 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>El Dr. Jos\u00e9 de Jes\u00fas Alba Romero, actual presidente de CONQUILAB, es Qu\u00edmico Farmac\u00e9utico Bi\u00f3logo con especialidad en Microbiolog\u00eda, con maestr\u00edas en Salud P\u00fablica y Bioqu\u00edmica Cl\u00ednica, as\u00ed como doctorado en Ciencias Biom\u00e9dicas. Su trayectoria integra docencia, investigaci\u00f3n, microbiolog\u00eda cl\u00ednica y liderazgo gremial, consolid\u00e1ndose como una voz importante en el impulso acad\u00e9mico y profesional de la medicina de laboratorio en M\u00e9xico.<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>Ixchel De La Luz Mart\u00ednez es Qu\u00edmico Farmac\u00e9utico Bi\u00f3logo por la Universidad Aut\u00f3noma de Guadalajara, M\u00e9xico y Posgrado en Biofarmacia y Farmacia Molecular por la Facultad de Farmacia de la Universidad Aut\u00f3noma del Estado de Morelos.\u00a0 Destacada Experta en Gen\u00e9tica Forense con m\u00e1s de 17 a\u00f1os de experiencia impulsando la excelencia cient\u00edfica, el control de calidad y los derechos humanos en investigaciones forenses. Perita auxiliar para tribunales federales y estatales de M\u00e9xico, especializ\u00e1ndose en huella gen\u00e9tica, an\u00e1lisis de v\u00ednculos biol\u00f3gicos y casos que involucran a ni\u00f1as, ni\u00f1os, adolescentes y grupos vulnerables.<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Jesus-Alba-Romero-Ixschel-de-la-Luz-Martinez-17.11.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Summit Microbiota 2026.<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>La Mtra. Yolanda Quintero G\u00f3mez es Nutricionista Dietista por la Universidad Nacional de Colombia, Magister\u00a0 en Educaci\u00f3n por la Universidad del Valle de M\u00e9xico y candidata a Mag\u00edster en Microbiota, Probi\u00f3ticos y Prebi\u00f3ticos por la Universidad Europea de Madrid. Es especialista en Administraci\u00f3n en Salud por la Pontificia Universidad Javeriana. Es Directora Acad\u00e9mica del Colegio Mexicano de Obesidad y Nutrici\u00f3n y fundadora y Directora Acad\u00e9mica del Summit Microbiota M\u00e9xico. Asimismo, es fundadora y presidenta de la Cumbre de Actualidades en Alimentaci\u00f3n y Nutrici\u00f3n hasta 2027. Es miembro fundadora de la Sociedad Mexicana de Inmunolog\u00eda y Nutrici\u00f3n y forma parte del comit\u00e9 directivo del Grupo Iberoamericano de Estudio del Microbioma y Nutrici\u00f3n. Tambi\u00e9n participa en el Grupo de Estudios en VIH\/SIDA y en el Consejo de Investigaci\u00f3n en Salud Perinatal del Departamento de Nutrici\u00f3n Perinatal en Puebla. Es docente en numerosas instituciones en M\u00e9xico y Latinoam\u00e9rica y autora y coautora de cap\u00edtulos de libros en las \u00e1reas de nutrici\u00f3n, VIH y microbiota, y editora en jefe de tres libros en desarrollo.<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Yolanda-Quintero-Gomez-2.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"777\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Yolanda-Quintero-Gomez-2.jpg\" alt=\"\" class=\"wp-image-32231\" style=\"aspect-ratio:0.55727193238123;width:261px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Yolanda-Quintero-Gomez-2.jpg 433w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Yolanda-Quintero-Gomez-2-167x300.jpg 167w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Yolanda-Quintero-Gomez-2-234x420.jpg 234w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/a><\/figure><\/div><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Yolanda-Quintero-Gomez-13.05.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Cambios en la Fundaci\u00f3n Jos\u00e9 Luis Casta\u00f1o y nuevos horizontes<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-721x1024.jpg\" alt=\"\" class=\"wp-image-32219\" style=\"aspect-ratio:0.7041276661040357;width:268px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-721x1024.jpg 721w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-211x300.jpg 211w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-768x1091.jpg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-696x989.jpg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-296x420.jpg 296w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez-600x853.jpg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Pastora-Rodriguez-Vazquez.jpg 829w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\" \/><\/a><\/figure><\/div>\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-1024x768.jpg\" alt=\"\" class=\"wp-image-32210\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-1024x768.jpg 1024w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-300x225.jpg 300w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-768x576.jpg 768w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-1536x1152.jpg 1536w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-80x60.jpg 80w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-265x198.jpg 265w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-696x522.jpg 696w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-1068x801.jpg 1068w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-560x420.jpg 560w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026-600x450.jpg 600w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Antonio-Buno-2026.jpg 1829w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>La Dra Pastora\u00a0Rodr\u00edguez V\u00e1zquez es Licenciada en Medicina y Cirug\u00eda, especialista en An\u00e1lisis Cl\u00ednicos. Jefa de Servicio de Laboratorio Cl\u00ednico del\u00a0Area Sanitaria A\u00a0Coru\u00f1a y Cee. Es presidenta de la Sociedad Espa\u00f1ola\u00a0de Medicina de Laboratorio\u00a0(Semedlab). Forma parte del Patronato\u00a0de la Fundaci\u00f3n Jos\u00e9 Luis Casta\u00f1o.<\/p>\n\n<p>\u00a0<\/p>\n<p>El Dr Antonio Bu\u00f1o Soto es Licenciado y Doctor en Medicina y Cirug\u00eda por la Universidad Aut\u00f3noma de Madrid, con formaci\u00f3n como especialista en An\u00e1lisis Cl\u00ednicos en el Hospital Universitario La Paz, Madrid, adonde se desempe\u00f1a como Jefe de Servicio An\u00e1lisis Cl\u00ednicos. Fue Presidente de la Sociedad Espa\u00f1ola de Medicina de Laboratorio durante cuatro a\u00f1os hasta diciembre del a\u00f1o pasado, y en estos momentos es a\u00fan Presidente de la Sociedad Espa\u00f1ola de Medicina de Laboratorio, antigua Fundaci\u00f3n Jose Luis Casta\u00f1o de esa Sociedad. Ha publicado numerosos trabajos en revistas cient\u00edficas, cap\u00edtulos de libros y ha recibido varios premios.<\/p><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/PODCAST-Antonio-Buno-Pastora-Rodriguez-19.53.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Podcast completo<\/figcaption><\/figure><h3 class=\"wp-block-heading has-text-align-center\">Historia de cient\u00edficos<\/h3><div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\"><div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><p>Gregor Johann Mendel fue un fraile agustino cat\u00f3lico y naturalista. Formul\u00f3, por medio de los trabajos que llev\u00f3 a cabo con diversa variedad de guisantes y arvejas, las hoy llamadas leyes de Mendel que dieron origen a la herencia gen\u00e9tica. Los primeros trabajos en gen\u00e9tica fueron realizados por Mendel.\u00a0<\/p><\/div>\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\"><figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gregor-Mendel.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"576\" src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gregor-Mendel.jpg\" alt=\"\" class=\"wp-image-32215\" style=\"aspect-ratio:0.6944520112594207;width:294px;height:auto\" srcset=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gregor-Mendel.jpg 400w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gregor-Mendel-208x300.jpg 208w, https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Gregor-Mendel-292x420.jpg 292w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><\/div><\/div><\/div><figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/www.infobioquimica.com\/new\/wp-content\/uploads\/2026\/05\/Mendel-1.mp3\"><\/audio><figcaption class=\"wp-element-caption\">Historia de cientificos<\/figcaption><\/figure>","protected":false},"excerpt":{"rendered":"<p>Microbiolog\u00eda cl\u00ednica: Incursionando en la epidemiolog\u00eda molecular bacteriana F\u00e1tima Rodr\u00edguez Acosta es Bioqu\u00edmica Cl\u00ednica con Especializaci\u00f3n en Metodolog\u00eda de la Investigaci\u00f3n por en Instituto de Investigaciones en Ciencias de la Salud, UNA, Paraguay. Es Magister en Ciencias Biom\u00e9dicas por el Instituto de Investigaciones en Ciencias de la Salud, Paraguay, y Diplomada en Interpretacion del Antibiograma [&hellip;]<\/p>\n","protected":false},"author":14117,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"twitterCardType":"","cardImageID":0,"cardImage":"","cardTitle":"","cardDesc":"","cardImageAlt":"","cardPlayer":"","cardPlayerWidth":0,"cardPlayerHeight":0,"cardPlayerStream":"","cardPlayerCodec":"","footnotes":""},"categories":[5,26,2],"tags":[546,440,442,773,438],"class_list":["post-32233","post","type-post","status-publish","format-standard","hentry","category-emisiones","category-noticias-bioquimicas","category-radio","tag-argentina","tag-el-microscopio","tag-radio","tag-radio-de-los-bioquimicos","tag-radio-el-microscopio"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/32233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/users\/14117"}],"replies":[{"embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/comments?post=32233"}],"version-history":[{"count":4,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/32233\/revisions"}],"predecessor-version":[{"id":32260,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/posts\/32233\/revisions\/32260"}],"wp:attachment":[{"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/media?parent=32233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/categories?post=32233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.infobioquimica.com\/new\/wp-json\/wp\/v2\/tags?post=32233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}